{"id":538,"date":"2021-09-29T07:50:49","date_gmt":"2021-09-29T05:50:49","guid":{"rendered":"https:\/\/homepages.lcc-toulouse.fr\/colombet\/?p=538"},"modified":"2021-09-29T08:02:58","modified_gmt":"2021-09-29T06:02:58","slug":"diskpart-suppression-des-partitions-cachees-sur-windows","status":"publish","type":"post","link":"https:\/\/homepages.lcc-toulouse.fr\/colombet\/diskpart-suppression-des-partitions-cachees-sur-windows\/","title":{"rendered":"diskpart &#8211; suppression des partitions cach\u00e9es sur Windows 10"},"content":{"rendered":"<p>Sous Windows 10, une partition est une division logique de l&rsquo;espace disponible du disque physique. Un disque peut contenir de nombreuses partitions et parfois il vous arrive d&rsquo;avoir besoin de les organiser. Des outils sp\u00e9cifiques existent, mais connaissez-vous celui natif de Windows ? Voici une synth\u00e8se des commandes pour supprimer les partitions cach\u00e9es (hidden).<\/p>\n<p><!--more--><\/p>\n<ul>\n<li>Depuis le prompt cmd <\/li>\n<li>Executer la commande <strong>diskpart<\/strong><\/li>\n<li>Pour lister les disques <strong>list disk<\/strong><\/li>\n<li>Pour s\u00e9lectionner le disque \u00e0 utiliser <strong>select disk NUMERO<\/strong><\/li>\n<li>Pour lister les partitions pr\u00e9sentes <strong>list partition<\/strong><\/li>\n<li>Pour s\u00e9lectionner la partition \u00e0 supprimer <strong>select partition NUMERO<\/strong><\/li>\n<li>Pour supprimer la partition s\u00e9lectionner <strong>delete partition<\/strong><\/li>\n<\/ul>\n<p><img decoding=\"async\" src=\"https:\/\/homepages.lcc-toulouse.fr\/colombet\/wp-content\/uploads\/sites\/2\/2021\/09\/16328946751402.jpg\" alt=\"\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sous Windows 10, une partition est une division logique de l&rsquo;espace disponible du disque physique. Un disque peut contenir de nombreuses partitions et parfois il vous arrive d&rsquo;avoir besoin de les organiser. Des outils sp\u00e9cifiques existent, mais connaissez-vous celui natif de Windows ? Voici une synth\u00e8se des commandes pour supprimer les partitions cach\u00e9es (hidden).<\/p>\n","protected":false},"author":13,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[78],"tags":[75,77,76],"class_list":["post-538","post","type-post","status-publish","format-standard","hentry","category-windows","tag-diskpart","tag-partition","tag-windows"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/paBEVZ-8G","jetpack_likes_enabled":false,"_links":{"self":[{"href":"https:\/\/homepages.lcc-toulouse.fr\/colombet\/wp-json\/wp\/v2\/posts\/538","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/homepages.lcc-toulouse.fr\/colombet\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/homepages.lcc-toulouse.fr\/colombet\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/homepages.lcc-toulouse.fr\/colombet\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/homepages.lcc-toulouse.fr\/colombet\/wp-json\/wp\/v2\/comments?post=538"}],"version-history":[{"count":1,"href":"https:\/\/homepages.lcc-toulouse.fr\/colombet\/wp-json\/wp\/v2\/posts\/538\/revisions"}],"predecessor-version":[{"id":539,"href":"https:\/\/homepages.lcc-toulouse.fr\/colombet\/wp-json\/wp\/v2\/posts\/538\/revisions\/539"}],"wp:attachment":[{"href":"https:\/\/homepages.lcc-toulouse.fr\/colombet\/wp-json\/wp\/v2\/media?parent=538"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/homepages.lcc-toulouse.fr\/colombet\/wp-json\/wp\/v2\/categories?post=538"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/homepages.lcc-toulouse.fr\/colombet\/wp-json\/wp\/v2\/tags?post=538"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}